{"id":130,"date":"2026-04-14T13:46:26","date_gmt":"2026-04-14T11:46:26","guid":{"rendered":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/?p=130"},"modified":"2026-04-15T09:24:48","modified_gmt":"2026-04-15T07:24:48","slug":"jornades-de-portes-obertes-el-cavallet-curs-2026-2027","status":"publish","type":"post","link":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/","title":{"rendered":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-134\" src=\"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg\" alt=\"\" width=\"1620\" height=\"1619\" srcset=\"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg 1620w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-300x300.jpg 300w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-1024x1024.jpg 1024w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-150x150.jpg 150w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-768x768.jpg 768w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-1536x1536.jpg 1536w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-75x75.jpg 75w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-850x850.jpg 850w, https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/\" \/>\n<meta property=\"og:site_name\" content=\"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/cavallcartroedu\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T11:46:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T07:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cgarcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cavallcartroedu\" \/>\n<meta name=\"twitter:site\" content=\"@cavallcartroedu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"cgarcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/\"},\"author\":{\"name\":\"cgarcia\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#\\\/schema\\\/person\\\/3b972af5d9eab406fc74cf186c32899f\"},\"headline\":\"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027\",\"datePublished\":\"2026-04-14T11:46:26+00:00\",\"dateModified\":\"2026-04-15T07:24:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2026\\\/04\\\/Cavallet-1.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/\",\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/\",\"name\":\"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2026\\\/04\\\/Cavallet-1.jpg\",\"datePublished\":\"2026-04-14T11:46:26+00:00\",\"dateModified\":\"2026-04-15T07:24:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2026\\\/04\\\/Cavallet-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2026\\\/04\\\/Cavallet-1.jpg\",\"width\":1620,\"height\":1619},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/2026\\\/04\\\/14\\\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#website\",\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/\",\"name\":\"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\",\"description\":\"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#organization\",\"name\":\"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\",\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2025\\\/09\\\/Logo-ebm-el-cavallet.png\",\"contentUrl\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/wp-content\\\/uploads\\\/sites\\\/45\\\/2025\\\/09\\\/Logo-ebm-el-cavallet.png\",\"width\":600,\"height\":348,\"caption\":\"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/cavallcartroedu\",\"https:\\\/\\\/x.com\\\/cavallcartroedu\",\"https:\\\/\\\/instagram.com\\\/cavallcartroedu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/#\\\/schema\\\/person\\\/3b972af5d9eab406fc74cf186c32899f\",\"name\":\"cgarcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g\",\"caption\":\"cgarcia\"},\"url\":\"https:\\\/\\\/www.cavallcartro.cat\\\/escoles\\\/ebm-el-cavallet\\\/author\\\/cgarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/","og_locale":"ca_ES","og_type":"article","og_title":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","og_url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/","og_site_name":"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","article_publisher":"https:\/\/facebook.com\/cavallcartroedu","article_published_time":"2026-04-14T11:46:26+00:00","article_modified_time":"2026-04-15T07:24:48+00:00","og_image":[{"width":1620,"height":1619,"url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg","type":"image\/jpeg"}],"author":"cgarcia","twitter_card":"summary_large_image","twitter_creator":"@cavallcartroedu","twitter_site":"@cavallcartroedu","twitter_misc":{"Escrit per":"cgarcia","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#article","isPartOf":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/"},"author":{"name":"cgarcia","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#\/schema\/person\/3b972af5d9eab406fc74cf186c32899f"},"headline":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027","datePublished":"2026-04-14T11:46:26+00:00","dateModified":"2026-04-15T07:24:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#organization"},"image":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/","url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/","name":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027 - EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","isPartOf":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#primaryimage"},"image":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg","datePublished":"2026-04-14T11:46:26+00:00","dateModified":"2026-04-15T07:24:48+00:00","breadcrumb":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#primaryimage","url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg","contentUrl":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2026\/04\/Cavallet-1.jpg","width":1620,"height":1619},{"@type":"BreadcrumbList","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/2026\/04\/14\/jornades-de-portes-obertes-el-cavallet-curs-2026-2027\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/"},{"@type":"ListItem","position":2,"name":"JORNADES DE PORTES OBERTES EL CAVALLET CURS 2026-2027"}]},{"@type":"WebSite","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#website","url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/","name":"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","description":"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","publisher":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#organization","name":"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca","url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#\/schema\/logo\/image\/","url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2025\/09\/Logo-ebm-el-cavallet.png","contentUrl":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-content\/uploads\/sites\/45\/2025\/09\/Logo-ebm-el-cavallet.png","width":600,"height":348,"caption":"EBM EL CAVALLET. Escola bressol municipal de Sant Andreu de la Barca"},"image":{"@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/cavallcartroedu","https:\/\/x.com\/cavallcartroedu","https:\/\/instagram.com\/cavallcartroedu"]},{"@type":"Person","@id":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/#\/schema\/person\/3b972af5d9eab406fc74cf186c32899f","name":"cgarcia","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7263ded1f97b93114eb056f8fea7536baf333e4c3fd57b7df620fca6f6840d?s=96&d=mm&r=g","caption":"cgarcia"},"url":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/author\/cgarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":3,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"predecessor-version":[{"id":138,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/posts\/130\/revisions\/138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/media\/134"}],"wp:attachment":[{"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cavallcartro.cat\/escoles\/ebm-el-cavallet\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}